{"id":2427,"date":"2026-02-10T11:22:38","date_gmt":"2026-02-10T10:22:38","guid":{"rendered":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/?p=2427"},"modified":"2026-03-02T12:04:27","modified_gmt":"2026-03-02T11:04:27","slug":"07-03-26-visite-guidee-au-musee-jenisch","status":"publish","type":"post","link":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/07-03-26-visite-guidee-au-musee-jenisch\/","title":{"rendered":"07.03.26 &#8211; Visite guid\u00e9e au Mus\u00e9e Jenisch"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.14.7&Prime; custom_padding=\u00a0\u00bb29px||16px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.14.7&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb custom_padding=\u00a0\u00bb9px||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb3.25&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1 dir=\"ltr\" style=\"text-align: center; font-size: 3em;\"><strong>Impressions du Japon<\/strong><\/h1>\n<h1 dir=\"ltr\" style=\"text-align: center; font-size: 3em;\"><strong>+<\/strong><\/h1>\n<h1 dir=\"ltr\" style=\"text-align: center; font-size: 3em;\"><strong>Kokoschka \u2013 Japomanie<\/strong><\/h1>\n<p>[\/et_pb_text][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\">7 mars 2026<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.14.7&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb custom_padding=\u00a0\u00bb2px||1px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb3.25&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.cerclesuissejapon.ch\/wordpress\/wp-content\/uploads\/2026\/02\/image-pour-visite-guidee.jpg\u00a0\u00bb title_text=\u00a0\u00bbimage pour visite guide\u0301e\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb10px||4px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div dir=\"ltr\" style=\"text-align: justify;\">\n<p>Le Cercle Suisse\u2013Japon a le plaisir de vous inviter \u00e0 une visite guid\u00e9e au Mus\u00e9e Jenisch de Vevey, consacr\u00e9e \u00e0 deux expositions qui explorent les <strong>\u00e9changes artistiques entre le Japon et l\u2019Europe<\/strong>.<\/p>\n<p>Cette visite permettra de d\u00e9couvrir des estampes japonaises majeures, r\u00e9alis\u00e9es par des artistes japonais de premier plan, ainsi que des \u0153uvres de <strong>Oskar Kokoschka<\/strong>, figure majeure de l\u2019expressionnisme autrichien, dont le travail a \u00e9t\u00e9 profond\u00e9ment influenc\u00e9 par l\u2019esth\u00e9tique japonaise.<br \/>Accompagn\u00e9s par un\u00b7e guide, nous pourrons replacer ces \u0153uvres dans leur contexte historique et artistique, et mieux comprendre les notions de japomanie, d\u2019influences crois\u00e9es et de r\u00e9interpr\u00e9tation culturelle.<\/p>\n<p>Plus d\u2019informations sur l\u2019exposition Kokoschka \u2013 Japomanie sont disponibles sur le site officiel du mus\u00e9e :\u00a0<span style=\"color: #993300;\"><strong><span style=\"text-decoration: underline;\"><a href=\"https:\/\/museejenisch.ch\/expositions\/kokoschka-japomanie\/\" target=\"_blank\" rel=\"noopener\" style=\"color: #993300; text-decoration: underline;\">Mus\u00e9e Jenisch &#8211; Exposition &#8211; Kokoschka &#8211; Japomanie<\/a><\/span><\/strong><\/span><\/p>\n<\/div>\n<p>[\/et_pb_text][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div dir=\"ltr\" style=\"text-align: justify;\">\n<h3 class=\"Corps\" style=\"text-align: justify;\"><strong>Informations pratiques<\/strong><\/h3>\n<\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div dir=\"ltr\" style=\"text-align: justify;\">\n<p><span style=\"color: #993300;\"><strong>Les places sont limit\u00e9es<\/strong><\/span> \u00e0 environ 20 personnes, les salles du mus\u00e9e \u00e9tant relativement petites.<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><strong>Date et Heure :<\/strong> Samedi 7 mars 2026 \u00e0 14h30<\/li>\n<li><strong>Lieu :<\/strong> Mus\u00e9e Jenisch, Avenue de la Gare 2, 1800 Vevey<\/li>\n<li><strong>Prix : <\/strong>\n<ul>\n<li>CHF 10.\u2013 pour les membres<\/li>\n<li>CHF 15.\u2013 pour les non-membres<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div dir=\"ltr\" style=\"text-align: justify;\">\n<h3 class=\"Corps\" style=\"text-align: justify;\"><strong>Moment convivial apr\u00e8s la visite<\/strong><\/h3>\n<\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb60.6px\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div dir=\"ltr\" style=\"text-align: justify;\">\n<p>Le mus\u00e9e ne permettant pas l\u2019organisation d\u2019une verr\u00e9e \u00e0 l\u2019int\u00e9rieur le week-end, celles et ceux qui le souhaitent pourront prolonger la visite autour d\u2019un verre dans un caf\u00e9 situ\u00e9 \u00e0 proximit\u00e9, par exemple au Caf\u00e9 Kym\u00e8m.<\/p>\n<\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 dir=\"ltr\" style=\"text-align: justify;\"><strong>Inscriptions<\/strong><\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<div dir=\"ltr\" style=\"text-align: justify;\">\n<p>Par e-mail \u00e0 :<strong>\u00a0<a href=\"mailto:comite@cerclesuissejapon.ch\">comite@cerclesuissejapon.ch<\/a><\/strong><br \/><span style=\"color: #236fa1;\"><\/span><\/p>\n<\/div>\n<p>[\/et_pb_text][et_pb_divider show_divider=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb min_height=\u00a0\u00bb17.8px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 dir=\"ltr\" style=\"text-align: justify;\"><strong>Paiement<\/strong><\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.14.7&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<table border=\"1\" style=\"border-collapse: collapse; width: 67.9448%; height: 96px;\">\n<tbody>\n<tr style=\"height: 24px;\">\n<td style=\"width: 49.8175%; height: 24px; text-align: left;\">Cercle Suisse Japon<\/td>\n<td style=\"width: 49.8175%; height: 24px; text-align: left;\">17-721689-5<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 49.8175%; height: 24px; text-align: left;\">IBAN<\/td>\n<td style=\"width: 49.8175%; height: 24px; text-align: left;\">CH55 0900 0000 1772 1689 5<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 49.8175%; height: 24px; text-align: left;\">BIC<\/td>\n<td style=\"width: 49.8175%; height: 24px; text-align: left;\">POFICHBEXXX<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 49.8175%; height: 24px; text-align: left;\">Code postal<\/td>\n<td style=\"width: 49.8175%; height: 24px; text-align: left;\">1164 Buchillon<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/i0.wp.com\/www.cerclesuissejapon.ch\/wordpress\/wp-content\/uploads\/2023\/08\/Screenshot-2023-08-28-at-18.42.18.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"442\" height=\"470\" src=\"https:\/\/i0.wp.com\/www.cerclesuissejapon.ch\/wordpress\/wp-content\/uploads\/2023\/08\/Screenshot-2023-08-28-at-18.42.18.png?resize=442%2C470&#038;ssl=1\" alt=\"\" class=\"wp-image-1870\" style=\"width: 198px; height: auto;\" srcset=\"https:\/\/i0.wp.com\/www.cerclesuissejapon.ch\/wordpress\/wp-content\/uploads\/2023\/08\/Screenshot-2023-08-28-at-18.42.18.png?w=442&amp;ssl=1 442w, https:\/\/i0.wp.com\/www.cerclesuissejapon.ch\/wordpress\/wp-content\/uploads\/2023\/08\/Screenshot-2023-08-28-at-18.42.18.png?resize=282%2C300&amp;ssl=1 282w\" sizes=\"auto, (max-width: 442px) 100vw, 442px\" \/><\/a><\/figure>\n<p><!-- \/divi:image --><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb1px||4px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb|5px||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p class=\"Corps\" style=\"text-align: left;\"><span style=\"font-family: 'Arial',sans-serif;\">Nous nous r\u00e9jouissons de vous y retrouver !<\/span><strong><span style=\"font-family: 'Arial',sans-serif;\"><\/span><\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Impressions du Japon + Kokoschka \u2013 Japomanie7 mars 2026 Le Cercle Suisse\u2013Japon a le plaisir de vous inviter \u00e0 une visite guid\u00e9e au Mus\u00e9e Jenisch de Vevey, consacr\u00e9e \u00e0 deux expositions qui explorent les \u00e9changes artistiques entre le Japon et l\u2019Europe. Cette visite permettra de d\u00e9couvrir des estampes japonaises majeures, r\u00e9alis\u00e9es par des artistes japonais [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_crdt_document":"","ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-2427","post","type-post","status-publish","format-standard","hentry","category-activites"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>07.03.26 - Visite guid\u00e9e au Mus\u00e9e Jenisch - Cercle Suisse Japon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cerclesuissejapon.ch\/wordpress\/07-03-26-visite-guidee-au-musee-jenisch\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"07.03.26 - Visite guid\u00e9e au Mus\u00e9e Jenisch - Cercle Suisse Japon\" \/>\n<meta property=\"og:description\" content=\"Impressions du Japon + Kokoschka \u2013 Japomanie7 mars 2026 Le Cercle Suisse\u2013Japon a le plaisir de vous inviter \u00e0 une visite guid\u00e9e au Mus\u00e9e Jenisch de Vevey, consacr\u00e9e \u00e0 deux expositions qui explorent les \u00e9changes artistiques entre le Japon et l\u2019Europe. Cette visite permettra de d\u00e9couvrir des estampes japonaises majeures, r\u00e9alis\u00e9es par des artistes japonais [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cerclesuissejapon.ch\/wordpress\/07-03-26-visite-guidee-au-musee-jenisch\/\" \/>\n<meta property=\"og:site_name\" content=\"Cercle Suisse Japon\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CercleSuisseJaponCSJ\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-10T10:22:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-02T11:04:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cerclesuissejapon.ch\/wordpress\/wp-content\/uploads\/2023\/08\/Screenshot-2023-08-28-at-18.42.18.png\" \/>\n<meta name=\"author\" content=\"Antoine Uldry\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antoine Uldry\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/07-03-26-visite-guidee-au-musee-jenisch\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/07-03-26-visite-guidee-au-musee-jenisch\\\/\"},\"author\":{\"name\":\"Antoine Uldry\",\"@id\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/#\\\/schema\\\/person\\\/935644a5e455670c51148e9960f71ea0\"},\"headline\":\"07.03.26 &#8211; Visite guid\u00e9e au Mus\u00e9e Jenisch\",\"datePublished\":\"2026-02-10T10:22:38+00:00\",\"dateModified\":\"2026-03-02T11:04:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/07-03-26-visite-guidee-au-musee-jenisch\\\/\"},\"wordCount\":819,\"publisher\":{\"@id\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/07-03-26-visite-guidee-au-musee-jenisch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Screenshot-2023-08-28-at-18.42.18.png\",\"articleSection\":[\"Activit\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/07-03-26-visite-guidee-au-musee-jenisch\\\/\",\"url\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/07-03-26-visite-guidee-au-musee-jenisch\\\/\",\"name\":\"07.03.26 - Visite guid\u00e9e au Mus\u00e9e Jenisch - Cercle Suisse Japon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/07-03-26-visite-guidee-au-musee-jenisch\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/07-03-26-visite-guidee-au-musee-jenisch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Screenshot-2023-08-28-at-18.42.18.png\",\"datePublished\":\"2026-02-10T10:22:38+00:00\",\"dateModified\":\"2026-03-02T11:04:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/07-03-26-visite-guidee-au-musee-jenisch\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/07-03-26-visite-guidee-au-musee-jenisch\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/07-03-26-visite-guidee-au-musee-jenisch\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Screenshot-2023-08-28-at-18.42.18.png?fit=442%2C470&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Screenshot-2023-08-28-at-18.42.18.png?fit=442%2C470&ssl=1\",\"width\":442,\"height\":470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/07-03-26-visite-guidee-au-musee-jenisch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"07.03.26 &#8211; Visite guid\u00e9e au Mus\u00e9e Jenisch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/\",\"name\":\"Cercle Suisse Japon\",\"description\":\"Actualit\u00e9s du Cercle Suisse Japon en Suisse romande\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/#organization\",\"name\":\"Cercle Suisse-Japon\",\"url\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/CSJ-logo-horizontal-hd.png?fit=1920%2C437&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/CSJ-logo-horizontal-hd.png?fit=1920%2C437&ssl=1\",\"width\":1920,\"height\":437,\"caption\":\"Cercle Suisse-Japon\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CercleSuisseJaponCSJ\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/#\\\/schema\\\/person\\\/935644a5e455670c51148e9960f71ea0\",\"name\":\"Antoine Uldry\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c78099824167ea771d74e3d812833f5c7c0cf91cdd9bd92e4491e396e7222ae9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c78099824167ea771d74e3d812833f5c7c0cf91cdd9bd92e4491e396e7222ae9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c78099824167ea771d74e3d812833f5c7c0cf91cdd9bd92e4491e396e7222ae9?s=96&d=mm&r=g\",\"caption\":\"Antoine Uldry\"},\"url\":\"https:\\\/\\\/www.cerclesuissejapon.ch\\\/wordpress\\\/author\\\/uldrycerclesuissejapon-ch\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"07.03.26 - Visite guid\u00e9e au Mus\u00e9e Jenisch - Cercle Suisse Japon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/07-03-26-visite-guidee-au-musee-jenisch\/","og_locale":"fr_FR","og_type":"article","og_title":"07.03.26 - Visite guid\u00e9e au Mus\u00e9e Jenisch - Cercle Suisse Japon","og_description":"Impressions du Japon + Kokoschka \u2013 Japomanie7 mars 2026 Le Cercle Suisse\u2013Japon a le plaisir de vous inviter \u00e0 une visite guid\u00e9e au Mus\u00e9e Jenisch de Vevey, consacr\u00e9e \u00e0 deux expositions qui explorent les \u00e9changes artistiques entre le Japon et l\u2019Europe. Cette visite permettra de d\u00e9couvrir des estampes japonaises majeures, r\u00e9alis\u00e9es par des artistes japonais [&hellip;]","og_url":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/07-03-26-visite-guidee-au-musee-jenisch\/","og_site_name":"Cercle Suisse Japon","article_publisher":"https:\/\/www.facebook.com\/CercleSuisseJaponCSJ\/","article_published_time":"2026-02-10T10:22:38+00:00","article_modified_time":"2026-03-02T11:04:27+00:00","og_image":[{"url":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/wp-content\/uploads\/2023\/08\/Screenshot-2023-08-28-at-18.42.18.png","type":"","width":"","height":""}],"author":"Antoine Uldry","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Antoine Uldry"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/07-03-26-visite-guidee-au-musee-jenisch\/#article","isPartOf":{"@id":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/07-03-26-visite-guidee-au-musee-jenisch\/"},"author":{"name":"Antoine Uldry","@id":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/#\/schema\/person\/935644a5e455670c51148e9960f71ea0"},"headline":"07.03.26 &#8211; Visite guid\u00e9e au Mus\u00e9e Jenisch","datePublished":"2026-02-10T10:22:38+00:00","dateModified":"2026-03-02T11:04:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/07-03-26-visite-guidee-au-musee-jenisch\/"},"wordCount":819,"publisher":{"@id":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/#organization"},"image":{"@id":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/07-03-26-visite-guidee-au-musee-jenisch\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/wp-content\/uploads\/2023\/08\/Screenshot-2023-08-28-at-18.42.18.png","articleSection":["Activit\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/07-03-26-visite-guidee-au-musee-jenisch\/","url":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/07-03-26-visite-guidee-au-musee-jenisch\/","name":"07.03.26 - Visite guid\u00e9e au Mus\u00e9e Jenisch - Cercle Suisse Japon","isPartOf":{"@id":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/07-03-26-visite-guidee-au-musee-jenisch\/#primaryimage"},"image":{"@id":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/07-03-26-visite-guidee-au-musee-jenisch\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/wp-content\/uploads\/2023\/08\/Screenshot-2023-08-28-at-18.42.18.png","datePublished":"2026-02-10T10:22:38+00:00","dateModified":"2026-03-02T11:04:27+00:00","breadcrumb":{"@id":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/07-03-26-visite-guidee-au-musee-jenisch\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cerclesuissejapon.ch\/wordpress\/07-03-26-visite-guidee-au-musee-jenisch\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/07-03-26-visite-guidee-au-musee-jenisch\/#primaryimage","url":"https:\/\/i0.wp.com\/www.cerclesuissejapon.ch\/wordpress\/wp-content\/uploads\/2023\/08\/Screenshot-2023-08-28-at-18.42.18.png?fit=442%2C470&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.cerclesuissejapon.ch\/wordpress\/wp-content\/uploads\/2023\/08\/Screenshot-2023-08-28-at-18.42.18.png?fit=442%2C470&ssl=1","width":442,"height":470},{"@type":"BreadcrumbList","@id":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/07-03-26-visite-guidee-au-musee-jenisch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/"},{"@type":"ListItem","position":2,"name":"07.03.26 &#8211; Visite guid\u00e9e au Mus\u00e9e Jenisch"}]},{"@type":"WebSite","@id":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/#website","url":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/","name":"Cercle Suisse Japon","description":"Actualit\u00e9s du Cercle Suisse Japon en Suisse romande","publisher":{"@id":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/#organization","name":"Cercle Suisse-Japon","url":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.cerclesuissejapon.ch\/wordpress\/wp-content\/uploads\/2022\/02\/CSJ-logo-horizontal-hd.png?fit=1920%2C437&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.cerclesuissejapon.ch\/wordpress\/wp-content\/uploads\/2022\/02\/CSJ-logo-horizontal-hd.png?fit=1920%2C437&ssl=1","width":1920,"height":437,"caption":"Cercle Suisse-Japon"},"image":{"@id":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CercleSuisseJaponCSJ\/"]},{"@type":"Person","@id":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/#\/schema\/person\/935644a5e455670c51148e9960f71ea0","name":"Antoine Uldry","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c78099824167ea771d74e3d812833f5c7c0cf91cdd9bd92e4491e396e7222ae9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c78099824167ea771d74e3d812833f5c7c0cf91cdd9bd92e4491e396e7222ae9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c78099824167ea771d74e3d812833f5c7c0cf91cdd9bd92e4491e396e7222ae9?s=96&d=mm&r=g","caption":"Antoine Uldry"},"url":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/author\/uldrycerclesuissejapon-ch\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/wp-json\/wp\/v2\/posts\/2427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/wp-json\/wp\/v2\/comments?post=2427"}],"version-history":[{"count":12,"href":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/wp-json\/wp\/v2\/posts\/2427\/revisions"}],"predecessor-version":[{"id":2452,"href":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/wp-json\/wp\/v2\/posts\/2427\/revisions\/2452"}],"wp:attachment":[{"href":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/wp-json\/wp\/v2\/media?parent=2427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/wp-json\/wp\/v2\/categories?post=2427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cerclesuissejapon.ch\/wordpress\/wp-json\/wp\/v2\/tags?post=2427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}